{"id":9632,"date":"2022-02-10T12:05:06","date_gmt":"2022-02-10T12:05:06","guid":{"rendered":"https:\/\/www.emhe.es\/?p=9632"},"modified":"2022-02-10T12:05:06","modified_gmt":"2022-02-10T12:05:06","slug":"las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil","status":"publish","type":"post","link":"https:\/\/www.emhe.es\/de\/las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil\/","title":{"rendered":"Neuheiten in Bezug auf die Zust\u00e4ndigkeit der Gerichte in Handelssachen"},"content":{"rendered":"Seit dem 14. Januar 2022 befindet sich der Entwurf des Organgesetzes zur \u00c4nderung des Organgesetzes 6\/1985 vom 1. Juli \u00fcber das Justizwesen in Bezug auf die Handelsgerichte in der \u00c4nderungsphase.<\/p>\n<p>Die Ver\u00f6ffentlichung dieses Gesetzes wird die Zust\u00e4ndigkeiten und die Verteilung der Fachgebiete, die derzeit den Handelsgerichten und den spezialisierten Abteilungen der Landgerichte in ganz Spanien zugewiesen sind, erheblich ver\u00e4ndern.<\/p>\n<p>Im Einzelnen werden die folgenden \u00c4nderungen vorgenommen:<\/p>\n<p>Erstens werden die Gerichte Erster Instanz zum Nachteil der Handelsgerichte \u00fcber Sammelklagen in Bezug auf allgemeine Vertragsbedingungen und Verbraucherschutz entscheiden.<\/p>\n<p>Au\u00dferdem werden sie sich mit Ausgleichs- und Unterst\u00fctzungsleistungen f\u00fcr Flugg\u00e4ste im Falle der Nichtbef\u00f6rderung und bei Annullierung oder gro\u00dfer Versp\u00e4tung von Fl\u00fcgen, mit den Rechten und Pflichten von Bahnreisenden, mit den Rechten von Busfahrg\u00e4sten und mit den Rechten von Passagieren im See- und Binnenschiffsverkehr befassen.<\/p>\n<p>Zweitens werden in Landeshauptst\u00e4dten, in denen es mehr als f\u00fcnf Handelsgerichte gibt, mindestens zwei von ihnen ausschlie\u00dflich \u00fcber Antr\u00e4ge auf Er\u00f6ffnung von Insolvenzverfahren nat\u00fcrlicher Personen entscheiden. In den Hauptst\u00e4dten mit mehr als einem und weniger als f\u00fcnf Gerichten werden diese F\u00e4lle ausschlie\u00dflich auf eines dieser Gerichte verteilt. Der Gesetzesentwurf bezieht sich nur auf die F\u00e4lle, in denen die insolvente Partei eine nat\u00fcrliche Person ist, die kein Unternehmer ist.<\/p>\n<p>Auch in der zweiten Instanz wird es diesen Zusammenhang geben, so dass es spezialisierte Gerichte und Abteilungen geben kann, die ausschlie\u00dflich auf Insolvenzverfahren oder auf geistiges und gewerbliches Eigentum, unlauteren Wettbewerb und Werbung spezialisiert sind.<\/p>\n<p>In Bezug auf die Spezialisierung der Gerichte auf Fragen des gewerblichen Rechtsschutzes, so w\u00e4re es nicht m\u00f6glich, an Orten, an denen es nicht mehr als f\u00fcnf Handelsgerichte gibt, eine ausschlie\u00dfliche Zust\u00e4ndigkeit f\u00fcr diese Fragen zu begr\u00fcnden. Daher ist es im Prinzip nur m\u00f6glich, sich auf die Gerichte und Abteilungen der Landgerichte von Madrid und Barcelona zu spezialisieren, da dies die einzigen beiden Provinzhauptst\u00e4dte sind, die die Voraussetzungen f\u00fcr die Spezialisierung erf\u00fcllen.<\/p>\n<p>Drittens und schlie\u00dflich verleiht diese Reform den spezialisierten Abteilungen der Landgerichte die Zust\u00e4ndigkeit f\u00fcr die Entscheidung \u00fcber Rechtsmittel gegen Entscheidungen, die den Verwaltungsrechtsweg des spanischen Patent- und Markenamts in Angelegenheiten des gewerblichen Rechtsschutzes aussch\u00f6pfen. In dieser Hinsicht k\u00f6nnten nur die Abteilungen der Landgerichte von Madrid, Barcelona und Valencia zust\u00e4ndig sein, da sie derzeit die einzigen spezialisierten Gerichte sind.<\/p>\n<p>Schlie\u00dflich ist daran zu erinnern, dass das spanische Patent- und Markenamt ab dem 14. Januar 2023 befugt sein wird, um die Ung\u00fcltigkeit und den Verfall von im Markengesetz geregelten Unterscheidungszeichen festzustellen.","protected":false},"excerpt":{"rendered":"<p>Seit dem 14. Januar 2022 befindet sich der Entwurf des Organgesetzes zur \u00c4nderung des Organgesetzes 6\/1985 vom 1. Juli \u00fcber das Justizwesen in Bezug auf die Handelsgerichte in der \u00c4nderungsphase.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[18],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Neuheiten in Bezug auf die Zust\u00e4ndigkeit der Gerichte in Handelssachen  - RocaJunyent_grupo - EMHE Legal<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emhe.es\/las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:es]Las novedades de la competencia de los tribunales en materia mercantil [:en]New developments in Spanish court\u2019s jurisdiction about commercial issues[:de]Neuheiten in Bezug auf die Zust\u00e4ndigkeit der Gerichte in Handelssachen [:] - RocaJunyent_grupo - EMHE Legal\" \/>\n<meta property=\"og:description\" content=\"[:es]Desde el 14 de enero de 2022 se encuentra en fase de enmiendas el Proyecto de Ley Org\u00e1nica de modificaci\u00f3n de la Ley Org\u00e1nica 6\/1985, de 1 de julio, del Poder Judicial, en materia de Juzgados de lo Mercantil.[:en]Since 14 January 2022, the Draft Organic Law amending Organic Law 6\/1985, of 1 July 1985, on the Judiciary, in relation to Commercial Courts, has been in the amendment phase.[:de]Seit dem 14. Januar 2022 befindet sich der Entwurf des Organgesetzes zur \u00c4nderung des Organgesetzes 6\/1985 vom 1. Juli \u00fcber das Justizwesen in Bezug auf die Handelsgerichte in der \u00c4nderungsphase.[:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emhe.es\/las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil\/\" \/>\n<meta property=\"og:site_name\" content=\"RocaJunyent_grupo - EMHE Legal\" \/>\n<meta property=\"article:published_time\" content=\"2022-02-10T12:05:06+00:00\" \/>\n<meta name=\"author\" content=\"EMHE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"EMHE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"7 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emhe.es\/las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil\/\",\"url\":\"https:\/\/www.emhe.es\/las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil\/\",\"name\":\"[:es]Las novedades de la competencia de los tribunales en materia mercantil [:en]New developments in Spanish court\u2019s jurisdiction about commercial issues[:de]Neuheiten in Bezug auf die Zust\u00e4ndigkeit der Gerichte in Handelssachen [:] - RocaJunyent_grupo - EMHE Legal\",\"isPartOf\":{\"@id\":\"https:\/\/www.emhe.es\/#website\"},\"datePublished\":\"2022-02-10T12:05:06+00:00\",\"dateModified\":\"2022-02-10T12:05:06+00:00\",\"author\":{\"@id\":\"https:\/\/www.emhe.es\/#\/schema\/person\/f30fb3874324d30bcb28b773bc9e46e8\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.emhe.es\/las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emhe.es\/las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emhe.es\/las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.emhe.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Las novedades de la competencia de los tribunales en materia mercantil\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emhe.es\/#website\",\"url\":\"https:\/\/www.emhe.es\/\",\"name\":\"RocaJunyent_grupo - EMHE Legal\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emhe.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.emhe.es\/#\/schema\/person\/f30fb3874324d30bcb28b773bc9e46e8\",\"name\":\"EMHE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.emhe.es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/92e82fdad437c34a114256d5c5141861?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/92e82fdad437c34a114256d5c5141861?s=96&d=mm&r=g\",\"caption\":\"EMHE\"},\"url\":\"https:\/\/www.emhe.es\/de\/author\/emhe-es\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:es]Las novedades de la competencia de los tribunales en materia mercantil [:en]New developments in Spanish court\u2019s jurisdiction about commercial issues[:de]Neuheiten in Bezug auf die Zust\u00e4ndigkeit der Gerichte in Handelssachen [:] - RocaJunyent_grupo - EMHE Legal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emhe.es\/las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil\/","og_locale":"de_DE","og_type":"article","og_title":"[:es]Las novedades de la competencia de los tribunales en materia mercantil [:en]New developments in Spanish court\u2019s jurisdiction about commercial issues[:de]Neuheiten in Bezug auf die Zust\u00e4ndigkeit der Gerichte in Handelssachen [:] - RocaJunyent_grupo - EMHE Legal","og_description":"[:es]Desde el 14 de enero de 2022 se encuentra en fase de enmiendas el Proyecto de Ley Org\u00e1nica de modificaci\u00f3n de la Ley Org\u00e1nica 6\/1985, de 1 de julio, del Poder Judicial, en materia de Juzgados de lo Mercantil.[:en]Since 14 January 2022, the Draft Organic Law amending Organic Law 6\/1985, of 1 July 1985, on the Judiciary, in relation to Commercial Courts, has been in the amendment phase.[:de]Seit dem 14. Januar 2022 befindet sich der Entwurf des Organgesetzes zur \u00c4nderung des Organgesetzes 6\/1985 vom 1. Juli \u00fcber das Justizwesen in Bezug auf die Handelsgerichte in der \u00c4nderungsphase.[:]","og_url":"https:\/\/www.emhe.es\/las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil\/","og_site_name":"RocaJunyent_grupo - EMHE Legal","article_published_time":"2022-02-10T12:05:06+00:00","author":"EMHE","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"EMHE","Gesch\u00e4tzte Lesezeit":"7 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.emhe.es\/las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil\/","url":"https:\/\/www.emhe.es\/las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil\/","name":"[:es]Las novedades de la competencia de los tribunales en materia mercantil [:en]New developments in Spanish court\u2019s jurisdiction about commercial issues[:de]Neuheiten in Bezug auf die Zust\u00e4ndigkeit der Gerichte in Handelssachen [:] - RocaJunyent_grupo - EMHE Legal","isPartOf":{"@id":"https:\/\/www.emhe.es\/#website"},"datePublished":"2022-02-10T12:05:06+00:00","dateModified":"2022-02-10T12:05:06+00:00","author":{"@id":"https:\/\/www.emhe.es\/#\/schema\/person\/f30fb3874324d30bcb28b773bc9e46e8"},"breadcrumb":{"@id":"https:\/\/www.emhe.es\/las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emhe.es\/las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.emhe.es\/las-novedades-de-la-competencia-de-los-tribunales-en-materia-mercantil\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.emhe.es\/"},{"@type":"ListItem","position":2,"name":"Las novedades de la competencia de los tribunales en materia mercantil"}]},{"@type":"WebSite","@id":"https:\/\/www.emhe.es\/#website","url":"https:\/\/www.emhe.es\/","name":"RocaJunyent_grupo - EMHE Legal","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emhe.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/www.emhe.es\/#\/schema\/person\/f30fb3874324d30bcb28b773bc9e46e8","name":"EMHE","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.emhe.es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/92e82fdad437c34a114256d5c5141861?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/92e82fdad437c34a114256d5c5141861?s=96&d=mm&r=g","caption":"EMHE"},"url":"https:\/\/www.emhe.es\/de\/author\/emhe-es\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/posts\/9632"}],"collection":[{"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/comments?post=9632"}],"version-history":[{"count":1,"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/posts\/9632\/revisions"}],"predecessor-version":[{"id":9633,"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/posts\/9632\/revisions\/9633"}],"wp:attachment":[{"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/media?parent=9632"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/categories?post=9632"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/tags?post=9632"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}