{"id":9570,"date":"2020-10-28T18:07:03","date_gmt":"2020-10-28T18:07:03","guid":{"rendered":"https:\/\/www.emhe.es\/?p=9570"},"modified":"2020-10-28T18:07:17","modified_gmt":"2020-10-28T18:07:17","slug":"la-infraccion-del-deber-de-depositar-las-cuentas-anuales","status":"publish","type":"post","link":"https:\/\/www.emhe.es\/de\/la-infraccion-del-deber-de-depositar-las-cuentas-anuales\/","title":{"rendered":"La infracci\u00f3n del deber de depositar las cuentas anuales"},"content":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-de\">Leider ist der Eintrag nur auf <a href=\"https:\/\/www.emhe.es\/es\/wp-json\/wp\/v2\/posts\/9570\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Espa\u00f1ol\">Europ\u00e4isches Spanisch<\/a> verf\u00fcgbar.<\/p>","protected":false},"excerpt":{"rendered":"<p class=\"qtranxs-available-languages-message qtranxs-available-languages-message-de\">Leider ist der Eintrag nur auf <a href=\"https:\/\/www.emhe.es\/es\/wp-json\/wp\/v2\/posts\/9570\" class=\"qtranxs-available-language-link qtranxs-available-language-link-es\" title=\"Espa\u00f1ol\">Europ\u00e4isches Spanisch<\/a> verf\u00fcgbar.<\/p>\n","protected":false},"author":2,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[1],"tags":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.5 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title><\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.emhe.es\/la-infraccion-del-deber-de-depositar-las-cuentas-anuales\/\" \/>\n<meta property=\"og:locale\" content=\"de_DE\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"[:es]La infracci\u00f3n del deber de depositar las cuentas anuales[:] - RocaJunyent_grupo - EMHE Legal\" \/>\n<meta property=\"og:description\" content=\"[:es]Entre las cuestiones que se plantean en la Sentencia del Tribunal Supremo de 28 de mayo de 2020, se encuentra la relativa a si la infracci\u00f3n por los administradores del deber de depositar las cuentas anuales en el Registro Mercantil es una causa de disoluci\u00f3n de la sociedad, con las importantes consecuencias para los administradores de responder \u201csolidariamente de las obligaciones sociales posteriores al acaecimiento de la causa legal de disoluci\u00f3n los administradores\u201d (art\u00edculo 367 TRLSC).[:]\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.emhe.es\/la-infraccion-del-deber-de-depositar-las-cuentas-anuales\/\" \/>\n<meta property=\"og:site_name\" content=\"RocaJunyent_grupo - EMHE Legal\" \/>\n<meta property=\"article:published_time\" content=\"2020-10-28T18:07:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2020-10-28T18:07:17+00:00\" \/>\n<meta name=\"author\" content=\"EMHE\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Verfasst von\" \/>\n\t<meta name=\"twitter:data1\" content=\"EMHE\" \/>\n\t<meta name=\"twitter:label2\" content=\"Gesch\u00e4tzte Lesezeit\" \/>\n\t<meta name=\"twitter:data2\" content=\"2 Minuten\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.emhe.es\/la-infraccion-del-deber-de-depositar-las-cuentas-anuales\/\",\"url\":\"https:\/\/www.emhe.es\/la-infraccion-del-deber-de-depositar-las-cuentas-anuales\/\",\"name\":\"[:es]La infracci\u00f3n del deber de depositar las cuentas anuales[:] - RocaJunyent_grupo - EMHE Legal\",\"isPartOf\":{\"@id\":\"https:\/\/www.emhe.es\/#website\"},\"datePublished\":\"2020-10-28T18:07:03+00:00\",\"dateModified\":\"2020-10-28T18:07:17+00:00\",\"author\":{\"@id\":\"https:\/\/www.emhe.es\/#\/schema\/person\/f30fb3874324d30bcb28b773bc9e46e8\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.emhe.es\/la-infraccion-del-deber-de-depositar-las-cuentas-anuales\/#breadcrumb\"},\"inLanguage\":\"de-DE\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.emhe.es\/la-infraccion-del-deber-de-depositar-las-cuentas-anuales\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.emhe.es\/la-infraccion-del-deber-de-depositar-las-cuentas-anuales\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Portada\",\"item\":\"https:\/\/www.emhe.es\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"La infracci\u00f3n del deber de depositar las cuentas anuales\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.emhe.es\/#website\",\"url\":\"https:\/\/www.emhe.es\/\",\"name\":\"RocaJunyent_grupo - EMHE Legal\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/www.emhe.es\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"de-DE\"},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.emhe.es\/#\/schema\/person\/f30fb3874324d30bcb28b773bc9e46e8\",\"name\":\"EMHE\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"de-DE\",\"@id\":\"https:\/\/www.emhe.es\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/92e82fdad437c34a114256d5c5141861?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/92e82fdad437c34a114256d5c5141861?s=96&d=mm&r=g\",\"caption\":\"EMHE\"},\"url\":\"https:\/\/www.emhe.es\/de\/author\/emhe-es\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"[:es]La infracci\u00f3n del deber de depositar las cuentas anuales[:] - RocaJunyent_grupo - EMHE Legal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.emhe.es\/la-infraccion-del-deber-de-depositar-las-cuentas-anuales\/","og_locale":"de_DE","og_type":"article","og_title":"[:es]La infracci\u00f3n del deber de depositar las cuentas anuales[:] - RocaJunyent_grupo - EMHE Legal","og_description":"[:es]Entre las cuestiones que se plantean en la Sentencia del Tribunal Supremo de 28 de mayo de 2020, se encuentra la relativa a si la infracci\u00f3n por los administradores del deber de depositar las cuentas anuales en el Registro Mercantil es una causa de disoluci\u00f3n de la sociedad, con las importantes consecuencias para los administradores de responder \u201csolidariamente de las obligaciones sociales posteriores al acaecimiento de la causa legal de disoluci\u00f3n los administradores\u201d (art\u00edculo 367 TRLSC).[:]","og_url":"https:\/\/www.emhe.es\/la-infraccion-del-deber-de-depositar-las-cuentas-anuales\/","og_site_name":"RocaJunyent_grupo - EMHE Legal","article_published_time":"2020-10-28T18:07:03+00:00","article_modified_time":"2020-10-28T18:07:17+00:00","author":"EMHE","twitter_card":"summary_large_image","twitter_misc":{"Verfasst von":"EMHE","Gesch\u00e4tzte Lesezeit":"2 Minuten"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/www.emhe.es\/la-infraccion-del-deber-de-depositar-las-cuentas-anuales\/","url":"https:\/\/www.emhe.es\/la-infraccion-del-deber-de-depositar-las-cuentas-anuales\/","name":"[:es]La infracci\u00f3n del deber de depositar las cuentas anuales[:] - RocaJunyent_grupo - EMHE Legal","isPartOf":{"@id":"https:\/\/www.emhe.es\/#website"},"datePublished":"2020-10-28T18:07:03+00:00","dateModified":"2020-10-28T18:07:17+00:00","author":{"@id":"https:\/\/www.emhe.es\/#\/schema\/person\/f30fb3874324d30bcb28b773bc9e46e8"},"breadcrumb":{"@id":"https:\/\/www.emhe.es\/la-infraccion-del-deber-de-depositar-las-cuentas-anuales\/#breadcrumb"},"inLanguage":"de-DE","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.emhe.es\/la-infraccion-del-deber-de-depositar-las-cuentas-anuales\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/www.emhe.es\/la-infraccion-del-deber-de-depositar-las-cuentas-anuales\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Portada","item":"https:\/\/www.emhe.es\/"},{"@type":"ListItem","position":2,"name":"La infracci\u00f3n del deber de depositar las cuentas anuales"}]},{"@type":"WebSite","@id":"https:\/\/www.emhe.es\/#website","url":"https:\/\/www.emhe.es\/","name":"RocaJunyent_grupo - EMHE Legal","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.emhe.es\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"de-DE"},{"@type":"Person","@id":"https:\/\/www.emhe.es\/#\/schema\/person\/f30fb3874324d30bcb28b773bc9e46e8","name":"EMHE","image":{"@type":"ImageObject","inLanguage":"de-DE","@id":"https:\/\/www.emhe.es\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/92e82fdad437c34a114256d5c5141861?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/92e82fdad437c34a114256d5c5141861?s=96&d=mm&r=g","caption":"EMHE"},"url":"https:\/\/www.emhe.es\/de\/author\/emhe-es\/"}]}},"_links":{"self":[{"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/posts\/9570"}],"collection":[{"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/comments?post=9570"}],"version-history":[{"count":0,"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/posts\/9570\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/media?parent=9570"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/categories?post=9570"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.emhe.es\/de\/wp-json\/wp\/v2\/tags?post=9570"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}